{"id":31,"count":9,"description":"","link":"https:\/\/www.dev.simplicity-homes.com\/blog\/category\/landscaping\/","name":"Landscaping","slug":"landscaping","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.dev.simplicity-homes.com\/blog\/wp-json\/wp\/v2\/categories\/31","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dev.simplicity-homes.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.dev.simplicity-homes.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.dev.simplicity-homes.com\/blog\/wp-json\/wp\/v2\/posts?categories=31"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}